{"id":6919,"date":"2025-10-03T17:04:59","date_gmt":"2025-10-03T22:04:59","guid":{"rendered":"https:\/\/cuidadoseguro.com.co\/csc3\/?page_id=6919"},"modified":"2026-07-15T11:15:15","modified_gmt":"2026-07-15T16:15:15","slug":"prueba","status":"publish","type":"page","link":"https:\/\/cuidadoseguro.com.co\/csc3\/","title":{"rendered":"prueba"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6919\" class=\"elementor elementor-6919\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13f6f305 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"13f6f305\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38f7f578\" data-id=\"38f7f578\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27b5e6f1 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"27b5e6f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fb6bc6e\" data-id=\"6fb6bc6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63c99db9 elementor--h-position-left elementor--v-position-middle elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"63c99db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay_speed&quot;:6000,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInRight\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-edb1508 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"BANER EFR WEB\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-32be151 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"NUEVO SLIDER_BANER BOLETIN 15\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-7b537aa swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"NUEVO SLIDER_BANER WEB 02\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Somos la IPS de Atenci\u00f3n Domiciliaria<\/div><div class=\"elementor-slide-description\">M\u00e1s Grande de Colombia<\/div><a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/nosotros-2\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-0147be6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"BOLETIN 25_BANER BOLETIN 15_BANER BOLETIN 15\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/boletin\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-a564155 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"BANER-NEW-PALEX\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Nos Certificamos<\/div><div class=\"elementor-slide-description\">En la metodolog\u00eda New Palex en Cuidados Paliativos por New Health Fundation<\/div><a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/2022\/11\/21\/__trashed\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-ce70e54 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"slider_pagina_3\"><\/div><a class=\"swiper-slide-inner\" href=\"http:\/\/www.agilitypremium.com\"><div class=\"swiper-slide-contents\"><\/div><\/a><\/div><div class=\"elementor-repeater-item-d936252 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"BANER WEB-01\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/codigo-de-conducta-y-buen-gobierno\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-md\">Consultalos aqu\u00ed<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e0dfc19 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7e0dfc19\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19c896b0\" data-id=\"19c896b0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4cae0b06 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4cae0b06\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7cde533c elementor-invisible\" data-id=\"7cde533c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3083a5 elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"f3083a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/atributos-de-cultura\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CULTURA CSC<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-67d08129 elementor-invisible\" data-id=\"67d08129\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-525ceb80 elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"525ceb80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/boletin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOLET\u00cdN  CSC<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-552518c elementor-invisible\" data-id=\"552518c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32cbdef4 elementor-align-center elementor-tablet-align-center elementor-mobile-align-center elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"32cbdef4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/nosotros-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">QUIENES SOMOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60ba5e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"60ba5e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28984b8\" data-id=\"28984b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58d5fed elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"58d5fed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69ab9c9f\" data-id=\"69ab9c9f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d505bc7 elementor-widget elementor-widget-heading\" data-id=\"5d505bc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contamos con m\u00e1s de 11 a\u00f1os de experiencia en <p> ATENCI\u00d3N CON CALIDAD<\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bc45b36 elementor-widget elementor-widget-text-editor\" data-id=\"1bc45b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"TextRun SCXW84720235 BCX2\" lang=\"ES-CO\" xml:lang=\"ES-CO\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84720235 BCX2\">Nuestro objetivo es satisfacer las expectativas de nuestros usuarios, pacientes y cuidadores, con altos est\u00e1ndares de humanismo, enfoc\u00e1ndonos en la seguridad del paciente, con una pol\u00edtica de mejoramiento continuo.<\/span><\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bce555a elementor-hidden-phone\" data-id=\"bce555a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46c2f564 elementor-widget elementor-widget-spacer\" data-id=\"46c2f564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3800b46 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3800b46\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73012b7\" data-id=\"73012b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dc2df5e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6dc2df5e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f7cefaa\" data-id=\"3f7cefaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1da4470f elementor-widget elementor-widget-heading\" data-id=\"1da4470f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Novedades\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2206ac5 elementor-widget elementor-widget-jkit_post_block\" data-id=\"2206ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_post_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-postblock postblock-type-3 jkit-pagination-disable post-element jeg_module___6a57e607aca42\"  data-id=\"jeg_module___6a57e607aca42\" data-settings=\"{&quot;post_type&quot;:&quot;post&quot;,&quot;number_post&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;post_offset&quot;:0,&quot;unique_content&quot;:&quot;disable&quot;,&quot;include_post&quot;:&quot;&quot;,&quot;exclude_post&quot;:&quot;&quot;,&quot;include_category&quot;:&quot;&quot;,&quot;exclude_category&quot;:&quot;&quot;,&quot;include_author&quot;:&quot;&quot;,&quot;include_tag&quot;:&quot;&quot;,&quot;exclude_tag&quot;:&quot;&quot;,&quot;r3d_category&quot;:&quot;&quot;,&quot;r3d_author&quot;:&quot;&quot;,&quot;wpr_template_type&quot;:&quot;&quot;,&quot;sort_by&quot;:&quot;latest&quot;,&quot;pagination_mode&quot;:&quot;disable&quot;,&quot;pagination_loadmore_text&quot;:&quot;Load More&quot;,&quot;pagination_loading_text&quot;:&quot;Loading...&quot;,&quot;pagination_number_post&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;pagination_scroll_limit&quot;:0,&quot;pagination_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;pagination_icon_position&quot;:&quot;before&quot;,&quot;st_category_position&quot;:&quot;center&quot;,&quot;sg_content_postblock_type&quot;:&quot;type-3&quot;,&quot;sg_content_element_order&quot;:&quot;title,meta,excerpt,read&quot;,&quot;sg_content_breakpoint&quot;:&quot;tablet&quot;,&quot;sg_content_title_html_tag&quot;:&quot;h4&quot;,&quot;sg_content_category_enable&quot;:&quot;&quot;,&quot;sg_content_excerpt_enable&quot;:&quot;yes&quot;,&quot;sg_content_excerpt_length&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:21,&quot;sizes&quot;:[]},&quot;sg_content_excerpt_more&quot;:&quot;...&quot;,&quot;sg_content_readmore_enable&quot;:&quot;yes&quot;,&quot;sg_content_readmore_icon&quot;:{&quot;value&quot;:&quot;fas fa-arrow-right&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_readmore_icon_position&quot;:&quot;after&quot;,&quot;sg_content_readmore_text&quot;:&quot;Leer m\\u00e1s&quot;,&quot;sg_content_comment_enable&quot;:&quot;yes&quot;,&quot;sg_content_comment_icon&quot;:{&quot;value&quot;:&quot;fas fa-comment&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_comment_icon_position&quot;:&quot;before&quot;,&quot;sg_content_meta_enable&quot;:&quot;yes&quot;,&quot;sg_content_meta_author_enable&quot;:&quot;yes&quot;,&quot;sg_content_meta_author_by_text&quot;:&quot;by&quot;,&quot;sg_content_meta_author_icon&quot;:{&quot;value&quot;:&quot;fas fa-user&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_meta_author_icon_position&quot;:&quot;before&quot;,&quot;sg_content_meta_date_enable&quot;:&quot;yes&quot;,&quot;sg_content_meta_date_type&quot;:&quot;published&quot;,&quot;sg_content_meta_date_format&quot;:&quot;default&quot;,&quot;sg_content_meta_date_format_custom&quot;:&quot;j F, Y&quot;,&quot;sg_content_meta_date_icon&quot;:{&quot;value&quot;:&quot;fas fa-clock&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_meta_date_icon_position&quot;:&quot;before&quot;,&quot;sg_content_image_size_imagesize_size&quot;:&quot;medium_large&quot;,&quot;paged&quot;:1,&quot;class&quot;:&quot;jkit_post_block&quot;}\"><div class=\"jkit-block-container\"><div class=\"jkit-posts jkit-ajax-flag\">\n            <article class=\"jkit-post post-8637 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n                    <div class=\"jkit-thumb\"><a aria-label=\"IPS Cuidado Seguro en Casa celebr\u00f3 10 a\u00f1os de compromiso con la atenci\u00f3n domiciliaria en el Caribe colombiano\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-celebro-10-anos-de-compromiso-con-la-atencion-domiciliaria-en-el-caribe-colombiano\/\"><div class=\"thumbnail-container \">\n            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/06\/DSC2025-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/06\/DSC2025-768x512.jpg 768w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/06\/DSC2025-300x200.jpg 300w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/06\/DSC2025-1024x683.jpg 1024w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/06\/DSC2025-1536x1024.jpg 1536w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/06\/DSC2025-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n        <\/div><\/a><\/div>\n                    <div class=\"jkit-postblock-content\"><h4 class=\"jkit-post-title\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-celebro-10-anos-de-compromiso-con-la-atencion-domiciliaria-en-el-caribe-colombiano\/\">IPS Cuidado Seguro en Casa celebr\u00f3 10 a\u00f1os de compromiso con la atenci\u00f3n domiciliaria en el Caribe colombiano<\/a>\n\t\t\t\t\t\t<\/h4><div class=\"jkit-post-meta\"><div class=\"jkit-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span><a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/author\/publicidad\/\">PUBLICIDAD CSC<\/a><\/div><div class=\"jkit-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>25 junio, 2026<\/div><\/div><div class=\"jkit-post-excerpt\"><p>Con la presencia de clientes, aliados estrat\u00e9gicos, proveedores, colaboradores e invitados especiales, IPS Cuidado Seguro en Casa conmemor\u00f3 sus 10 a\u00f1os...<\/p><\/div><div class=\"jkit-post-meta-bottom\">\n\t\t\t\t\t\t\t<div class=\"jkit-meta-readmore icon-position-after\">\n                <a title=\"IPS Cuidado Seguro en Casa celebr\u00f3 10 a\u00f1os de compromiso con la atenci\u00f3n domiciliaria en el Caribe colombiano\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-celebro-10-anos-de-compromiso-con-la-atencion-domiciliaria-en-el-caribe-colombiano\/\" class=\"jkit-readmore\">Leer m\u00e1s<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div><div class=\"jkit-meta-comment icon-position-before\">\n                <a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-celebro-10-anos-de-compromiso-con-la-atencion-domiciliaria-en-el-caribe-colombiano\/#respond\" >\n                    <i aria-hidden=\"true\" class=\"fas fa-comment\"><\/i><span>0<\/span>\n                <\/a>\n            <\/div>\n\t\t\t\t\t\t<\/div><\/div>\n                <\/article><article class=\"jkit-post post-8565 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n                    <div class=\"jkit-thumb\"><a aria-label=\"IPS CUIDADO SEGURO EN CASA PRESENT\u00d3 RESULTADOS DE SU GESTI\u00d3N 2025\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presento-resultados-de-su-gestion-2025\/\"><div class=\"thumbnail-container \">\n            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"515\" src=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/DSC1965-01-768x515.webp\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/DSC1965-01-768x515.webp 768w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/DSC1965-01-300x201.webp 300w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/DSC1965-01-1024x687.webp 1024w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/DSC1965-01.webp 1275w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n        <\/div><\/a><\/div>\n                    <div class=\"jkit-postblock-content\"><h4 class=\"jkit-post-title\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presento-resultados-de-su-gestion-2025\/\">IPS CUIDADO SEGURO EN CASA PRESENT\u00d3 RESULTADOS DE SU GESTI\u00d3N 2025<\/a>\n\t\t\t\t\t\t<\/h4><div class=\"jkit-post-meta\"><div class=\"jkit-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span><a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/author\/publicidad\/\">PUBLICIDAD CSC<\/a><\/div><div class=\"jkit-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>26 mayo, 2026<\/div><\/div><div class=\"jkit-post-excerpt\"><p>En la audiencia p\u00fablica de Rendici\u00f3n de cuentas 2025, Realizada este lunes 25 de mayo de 2026, IPS Cuidado Seguro en...<\/p><\/div><div class=\"jkit-post-meta-bottom\">\n\t\t\t\t\t\t\t<div class=\"jkit-meta-readmore icon-position-after\">\n                <a title=\"IPS CUIDADO SEGURO EN CASA PRESENT\u00d3 RESULTADOS DE SU GESTI\u00d3N 2025\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presento-resultados-de-su-gestion-2025\/\" class=\"jkit-readmore\">Leer m\u00e1s<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div><div class=\"jkit-meta-comment icon-position-before\">\n                <a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presento-resultados-de-su-gestion-2025\/#respond\" >\n                    <i aria-hidden=\"true\" class=\"fas fa-comment\"><\/i><span>0<\/span>\n                <\/a>\n            <\/div>\n\t\t\t\t\t\t<\/div><\/div>\n                <\/article><article class=\"jkit-post post-8507 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n                    <div class=\"jkit-thumb\"><a aria-label=\"IPS Cuidado Seguro en Casa presente en conmemoraci\u00f3n del D\u00eda Mundial de la Seguridad y Salud en el Trabajo\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presente-en-conmemoracion-del-dia-mundial-de-la-seguridad-y-salud-en-el-trabajo\/\"><div class=\"thumbnail-container \">\n            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-28-at-12.40.19-PM-768x576.jpeg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-28-at-12.40.19-PM-768x576.jpeg 768w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-28-at-12.40.19-PM-300x225.jpeg 300w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-28-at-12.40.19-PM-1024x768.jpeg 1024w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-28-at-12.40.19-PM.jpeg 1280w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n        <\/div><\/a><\/div>\n                    <div class=\"jkit-postblock-content\"><h4 class=\"jkit-post-title\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presente-en-conmemoracion-del-dia-mundial-de-la-seguridad-y-salud-en-el-trabajo\/\">IPS Cuidado Seguro en Casa presente en conmemoraci\u00f3n del D\u00eda Mundial de la Seguridad y Salud en el Trabajo<\/a>\n\t\t\t\t\t\t<\/h4><div class=\"jkit-post-meta\"><div class=\"jkit-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span><a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/author\/publicidad\/\">PUBLICIDAD CSC<\/a><\/div><div class=\"jkit-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>4 mayo, 2026<\/div><\/div><div class=\"jkit-post-excerpt\"><p>IPS Cuidado Seguro en Casa presente en conmemoraci\u00f3n del D\u00eda Mundial de la Seguridad y Salud en el Trabajo En el...<\/p><\/div><div class=\"jkit-post-meta-bottom\">\n\t\t\t\t\t\t\t<div class=\"jkit-meta-readmore icon-position-after\">\n                <a title=\"IPS Cuidado Seguro en Casa presente en conmemoraci\u00f3n del D\u00eda Mundial de la Seguridad y Salud en el Trabajo\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presente-en-conmemoracion-del-dia-mundial-de-la-seguridad-y-salud-en-el-trabajo\/\" class=\"jkit-readmore\">Leer m\u00e1s<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div><div class=\"jkit-meta-comment icon-position-before\">\n                <a href=\"https:\/\/cuidadoseguro.com.co\/csc3\/ips-cuidado-seguro-en-casa-presente-en-conmemoracion-del-dia-mundial-de-la-seguridad-y-salud-en-el-trabajo\/#respond\" >\n                    <i aria-hidden=\"true\" class=\"fas fa-comment\"><\/i><span>0<\/span>\n                <\/a>\n            <\/div>\n\t\t\t\t\t\t<\/div><\/div>\n                <\/article>\n        <\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48ca9a85 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"48ca9a85\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-318ef9fe\" data-id=\"318ef9fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c2910cf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3c2910cf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5ca14619\" data-id=\"5ca14619\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-607c47b4 elementor-widget elementor-widget-heading\" data-id=\"607c47b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros Atributos de Cultura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d7a234b elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"2d7a234b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/atributos-de-cultura\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leer M\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12ae70e6 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no elementor-invisible\" data-id=\"12ae70e6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5ac0cf94\" data-id=\"5ac0cf94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-523b99eb elementor-widget elementor-widget-image\" data-id=\"523b99eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/elementor\/thumbs\/IMG_5173-qcgdov6f7cw6f5wx6fackznonrcojc2lf1ji7cpc0g.jpg\" title=\"IMG_5173\" alt=\"IMG_5173\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-70e6b08a\" data-id=\"70e6b08a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68df2ecc elementor-widget elementor-widget-image\" data-id=\"68df2ecc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2023\/09\/IMG_7122-2-scaled.jpg\" class=\"attachment-full size-full wp-image-4790\" alt=\"\" srcset=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2023\/09\/IMG_7122-2-scaled.jpg 2560w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2023\/09\/IMG_7122-2-300x200.jpg 300w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2023\/09\/IMG_7122-2-1024x683.jpg 1024w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2023\/09\/IMG_7122-2-768x512.jpg 768w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2023\/09\/IMG_7122-2-1536x1024.jpg 1536w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2023\/09\/IMG_7122-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5e6edd5c\" data-id=\"5e6edd5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f66d09d elementor-widget elementor-widget-image\" data-id=\"4f66d09d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/elementor\/thumbs\/DSC0667-1024x683-1-pz1xe2zsoar8zv6kbdj15d6wqmb27r1mneg0lg4t8w.jpg\" title=\"DSC0667-1024&#215;683\" alt=\"DSC0667-1024x683\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54ec01d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"54ec01d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a376608\" data-id=\"5a376608\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-306526bc animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no elementor-invisible\" data-id=\"306526bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1acbd25d\" data-id=\"1acbd25d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79c1cbda elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"79c1cbda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"jki jki-user-check-solid\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e818b98 elementor-widget elementor-widget-heading\" data-id=\"3e818b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">16.066<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46f6813 elementor-widget elementor-widget-heading\" data-id=\"46f6813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pacientes Activos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7a49445b\" data-id=\"7a49445b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71500a15 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"71500a15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"jki jki-file-medical-alt-solid\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1128c860 elementor-widget elementor-widget-heading\" data-id=\"1128c860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">33<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-629c351e elementor-widget elementor-widget-heading\" data-id=\"629c351e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicios Ofertados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-be1b453\" data-id=\"be1b453\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cd170d1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4cd170d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"hm hm-location-pointer\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45870088 elementor-widget elementor-widget-heading\" data-id=\"45870088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">554<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36e5ae23 elementor-widget elementor-widget-heading\" data-id=\"36e5ae23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zonas del Territorio Nacional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-53f6cbc4\" data-id=\"53f6cbc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24a101c4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"24a101c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"jki jki-doctor-light\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b79b8af elementor-widget elementor-widget-heading\" data-id=\"1b79b8af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1.464<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-293a3922 elementor-widget elementor-widget-heading\" data-id=\"293a3922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Profesionales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6661915c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6661915c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7cc83fc3\" data-id=\"7cc83fc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e836041 elementor-widget elementor-widget-spacer\" data-id=\"6e836041\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-735e49dc elementor-widget elementor-widget-heading\" data-id=\"735e49dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mira  Nuestros Videos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fec7fb0 elementor-widget elementor-widget-text-editor\" data-id=\"4fec7fb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ent\u00e9rate de las actividades que realizamos en nuestro quehacer diario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e6a9523 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2e6a9523\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7345266f\" data-id=\"7345266f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11e6f705 elementor-widget elementor-widget-video\" data-id=\"11e6f705\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=GdcbKO8D7CQ&amp;t=2s&amp;ab_channel=IPSCuidadoSeguroenCasa&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7132abb4\" data-id=\"7132abb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-628fb951 elementor-widget elementor-widget-heading\" data-id=\"628fb951\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lista de Videos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4833e775 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4833e775\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1906e9e8\" data-id=\"1906e9e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75914d2e elementor-widget elementor-widget-video\" data-id=\"75914d2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=OGoxLVzyLM8&amp;t=2667s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e4a2d3 elementor-widget elementor-widget-video\" data-id=\"43e4a2d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=jk_8hX3pDQE&amp;t=18s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1558c6db elementor-widget elementor-widget-video\" data-id=\"1558c6db\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=ooqZPjWPHrs&amp;t=10s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70172c49 elementor-widget elementor-widget-button\" data-id=\"70172c49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.youtube.com\/@ipscuidadoseguroencasa2009\/featured\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leer M\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ab3c842\" data-id=\"5ab3c842\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3831044 elementor-widget__width-initial elementor-widget elementor-widget-facebook-page\" data-id=\"3831044\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"facebook-page.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-facebook-widget fb-page\" data-href=\"https:\/\/www.facebook.com\/cuidadoseguroencasa\/?ref=embed_page\" data-tabs=\"timeline\" data-height=\"521px\" data-width=\"500px\" data-small-header=\"false\" data-hide-cover=\"false\" data-show-facepile=\"true\" data-hide-cta=\"false\" style=\"min-height: 1px;height:521px\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58208e60 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"58208e60\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1530658b\" data-id=\"1530658b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aa44c97 elementor-widget elementor-widget-spacer\" data-id=\"1aa44c97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15471593 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"15471593\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61ece63b\" data-id=\"61ece63b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a6736cf elementor-widget elementor-widget-heading\" data-id=\"3a6736cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COBERTURA CON PROYECCI\u00d3N EN  TODO\n <p> EL TERRITORIO NACIONAL <\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4626ab84 elementor-widget elementor-widget-text-editor\" data-id=\"4626ab84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestra amplia cobertura geogr\u00e1fica incluye m\u00e1s de&nbsp; <strong>668 zonas<\/strong>, entre veredas, municipios y corregimientos del territorio nacional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5824a65e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5824a65e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c4e4659\" data-id=\"6c4e4659\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11cb3ece elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"11cb3ece\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4efe01ae\" data-id=\"4efe01ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d704716 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6d704716\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"jki jki-map-marked-alt-solid\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dccdd13 elementor-widget elementor-widget-heading\" data-id=\"1dccdd13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">122<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c073673 elementor-widget elementor-widget-heading\" data-id=\"6c073673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Municipios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-647da797\" data-id=\"647da797\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a5396ff elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7a5396ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"jki jki-road-solid\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99f1249 elementor-widget elementor-widget-heading\" data-id=\"99f1249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">314<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a5d6666 elementor-widget elementor-widget-heading\" data-id=\"2a5d6666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Corregimientos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2595aa82\" data-id=\"2595aa82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7ae234 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1b7ae234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"jki jki-broadcast-tower-solid\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f245dd6 elementor-widget elementor-widget-heading\" data-id=\"7f245dd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">232<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a12b735 elementor-widget elementor-widget-heading\" data-id=\"1a12b735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Veredas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-47e0021d\" data-id=\"47e0021d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e8bfe12 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"2e8bfe12\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;365&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Operaci\u00f3n Efectiva los <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">365<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\"> D\u00edas del A\u00f1o<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-20fca057 elementor-widget elementor-widget-heading\" data-id=\"20fca057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros usuarios recomiendan<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f78d35f elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5f78d35f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-57449e40\" data-id=\"57449e40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-524a0f41 elementor-widget elementor-widget-heading\" data-id=\"524a0f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transformamos vidas, brindando con pasio\u0301n, servicios, c\u00e1lidos y efectivos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42e817 elementor-align-left elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"42e817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/cuidadoseguro.com.co\/csc3\/servicios\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Servicios<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5fadd2b7\" data-id=\"5fadd2b7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc825bf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"cc825bf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68fa92bc\" data-id=\"68fa92bc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54ea2a86 elementor-widget elementor-widget-spacer\" data-id=\"54ea2a86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Somos la IPS de Atenci\u00f3n DomiciliariaM\u00e1s Grande de ColombiaLeer M\u00e1sLeer M\u00e1sNos CertificamosEn la metodolog\u00eda New Palex en Cuidados Paliativos por New Health FundationLeer M\u00e1sConsultalos aqu\u00ed CULTURA CSC BOLET\u00cdN CSC QUIENES SOMOS Contamos con m\u00e1s de 11 a\u00f1os de experiencia en ATENCI\u00d3N CON CALIDAD Nuestro objetivo es satisfacer las expectativas de nuestros usuarios, pacientes y cuidadores, con altos est\u00e1ndares de humanismo, enfoc\u00e1ndonos en la seguridad del paciente, con una pol\u00edtica de mejoramiento continuo. Novedades edit post IPS Cuidado Seguro en Casa celebr\u00f3 10 a\u00f1os de compromiso con la atenci\u00f3n domiciliaria en el Caribe colombiano byPUBLICIDAD CSC25 junio, 2026 Con la presencia de clientes, aliados estrat\u00e9gicos, proveedores, colaboradores e invitados especiales, IPS Cuidado Seguro en Casa conmemor\u00f3 sus 10 a\u00f1os&#8230; Leer m\u00e1s 0 edit post IPS CUIDADO SEGURO EN CASA PRESENT\u00d3 RESULTADOS DE SU GESTI\u00d3N 2025 byPUBLICIDAD CSC26 mayo, 2026 En la audiencia p\u00fablica de Rendici\u00f3n de cuentas 2025, Realizada este lunes 25 de mayo de 2026, IPS Cuidado Seguro en&#8230; Leer m\u00e1s 0 edit post IPS Cuidado Seguro en Casa presente en conmemoraci\u00f3n del D\u00eda Mundial de la Seguridad y Salud en el Trabajo byPUBLICIDAD CSC4 mayo, 2026 IPS Cuidado Seguro en Casa presente en conmemoraci\u00f3n del D\u00eda Mundial de la Seguridad y Salud en el Trabajo En el&#8230; Leer m\u00e1s 0 Nuestros Atributos de Cultura Leer M\u00e1s 16.066 Pacientes Activos 33 Servicios Ofertados 554 Zonas del Territorio Nacional 1.464 Profesionales Mira Nuestros Videos Ent\u00e9rate de las actividades que realizamos en nuestro quehacer diario. https:\/\/www.youtube.com\/watch?v=GdcbKO8D7CQ&#038;t=2s&#038;ab_channel=IPSCuidadoSeguroenCasa Lista de Videos Leer M\u00e1s COBERTURA CON PROYECCI\u00d3N EN TODO EL TERRITORIO NACIONAL Nuestra amplia cobertura geogr\u00e1fica incluye m\u00e1s de&nbsp; 668 zonas, entre veredas, municipios y corregimientos del territorio nacional. 122 Municipios 314 Corregimientos 232 Veredas Operaci\u00f3n Efectiva los 365 D\u00edas del A\u00f1o Nuestros usuarios recomiendan Transformamos vidas, brindando con pasio\u0301n, servicios, c\u00e1lidos y efectivos. Servicios<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_angie_page":false,"footnotes":""},"class_list":["post-6919","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages\/6919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/comments?post=6919"}],"version-history":[{"count":63,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages\/6919\/revisions"}],"predecessor-version":[{"id":8695,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages\/6919\/revisions\/8695"}],"wp:attachment":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/media?parent=6919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}