{"id":497,"date":"2022-07-26T11:32:16","date_gmt":"2022-07-26T16:32:16","guid":{"rendered":"https:\/\/cuidadoseguro.com.co\/csc3\/?page_id=497"},"modified":"2026-03-31T11:55:46","modified_gmt":"2026-03-31T16:55:46","slug":"servicio-de-tecnologia-en-salud","status":"publish","type":"page","link":"https:\/\/cuidadoseguro.com.co\/csc3\/servicio-de-tecnologia-en-salud\/","title":{"rendered":"Servicio de Tecnolog\u00eda en Salud"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"497\" class=\"elementor elementor-497\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d1ccb8f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2d1ccb8f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/cuidadoseguro.com.co\\\/csc3\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/3d-rendering-interior-isolated-empty-bed-in-hospi-2022-01-19-00-20-19-utc-1.mp4&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22ac0df2\" data-id=\"22ac0df2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-581c082e elementor-widget elementor-widget-heading\" data-id=\"581c082e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44cd0548\" data-id=\"44cd0548\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fe810ba elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6fe810ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4de2d858\" data-id=\"4de2d858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-418c8741 elementor-widget elementor-widget-heading\" data-id=\"418c8741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tecnolog\u00eda en Salud<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-405007a9 elementor-widget elementor-widget-text-editor\" data-id=\"405007a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Realizamos el suministro, transporte e instalaci\u00f3n de tecnolog\u00eda en salud (equipos biom\u00e9dicos, biom\u00e9tricos, insumos, dispositivos) y materiales necesarios para completar una \u00f3ptima recuperaci\u00f3n del paciente en su domicilio.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:columns --><\/p>\n<div>\n<p><!-- wp:column --><\/p>\n<div>\n<p><!-- wp:paragraph --><\/p>\n<div>Concentradores<\/div>\n<div>\n<p style=\"margin: 0cm;\">Balas de ox\u00edgeno<\/p>\n<p style=\"margin: 0cm;\">Aspiradores<\/p>\n<p style=\"margin: 0cm;\">Nebulizadores<\/p>\n<p style=\"margin: 0cm;\">Bombas de infusi\u00f3n<\/p>\n<p style=\"margin: 0cm;\">B-PAP<\/p>\n<p style=\"margin: 0cm;\">C-PAP<\/p>\n<p style=\"margin: 0cm;\">Camas hospitalarias<\/p>\n<p style=\"margin: 0cm;\">Colchones anti escaras<\/p>\n<p style=\"margin: 0cm;\">Bombas de sistema de presi\u00f3n negativa<\/p>\n<p>Monitores de signos vitales<\/p><p>Ventiladores<\/p>\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-717d9888\" data-id=\"717d9888\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-450779e2 elementor-widget elementor-widget-image\" data-id=\"450779e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"509\" src=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2022\/09\/doctor-holding-an-oxygen-cylinder-and-a-mask-attac-2022-05-30-15-47-46-utc-1024x652.jpg\" class=\"attachment-large size-large wp-image-1026\" alt=\"\" srcset=\"https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2022\/09\/doctor-holding-an-oxygen-cylinder-and-a-mask-attac-2022-05-30-15-47-46-utc-1024x652.jpg 1024w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2022\/09\/doctor-holding-an-oxygen-cylinder-and-a-mask-attac-2022-05-30-15-47-46-utc-300x191.jpg 300w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2022\/09\/doctor-holding-an-oxygen-cylinder-and-a-mask-attac-2022-05-30-15-47-46-utc-768x489.jpg 768w, https:\/\/cuidadoseguro.com.co\/csc3\/wp-content\/uploads\/2022\/09\/doctor-holding-an-oxygen-cylinder-and-a-mask-attac-2022-05-30-15-47-46-utc.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-722ced1a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"722ced1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ae53c17\" data-id=\"3ae53c17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-211826ab elementor-widget elementor-widget-heading\" data-id=\"211826ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transformamos vidas, brindando con pasio\u0301n, servicios c\u00e1lidos y efectivos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27300bb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"27300bb2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42420c7f\" data-id=\"42420c7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7da28cc9 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7da28cc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33defcbd elementor-widget elementor-widget-heading\" data-id=\"33defcbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros Atributos de Cultura\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a1ee0b4 elementor-widget elementor-widget-text-editor\" data-id=\"5a1ee0b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Comprometidos con el bienestar de todos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50af28e8 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no elementor-invisible\" data-id=\"50af28e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7bd74bb6\" data-id=\"7bd74bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-179a7c5f jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"179a7c5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module___6a5804c9d4033\" ><div class=\"jkit-icon-box-wrapper hover-from-bottom\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" data-name=\"Capa 1\" viewBox=\"0 0 650 650\"><defs><style>      .cls-1 {        fill: #184c95;        fill-rule: evenodd;      }    <\/style><\/defs><path class=\"cls-1\" d=\"M529.07,52.64c-54.72,8.48-113.91,44.99-163.88,101.14-17.03,19.22-33.64,43.48-45.37,66.03-3.35,6.44-6.14,11.6-6.42,11.6-.14,0-1.68-3.01-3.49-6.76-8.1-17.29-30.01-46.17-49.97-65.71-15.63-15.35-40.48-33.28-57.09-41.34-9.63-4.72-31.83-12.78-41.18-15.14-25.41-6.23-48.58-4.94-71.19,3.86-29.59,11.49-51.93,32.75-60.3,57.55-5.58,16.32-6.84,26.3-6,45.95,1.95,42.62,18.29,84.82,54.44,141.29,15.49,24.16,31.55,46.92,40.9,58.19,2.65,3.11,4.75,5.91,4.75,6.23,0,.97,24.01,30.28,36.57,44.56,6.56,7.41,24.29,27.59,39.36,44.99,15.22,17.39,28.2,32.1,28.9,32.75,3.49,3.22,15.63,16.54,25.27,27.49,13.68,15.46,18.15,19.54,29.73,27.38,7.96,5.37,10.05,6.34,14.38,6.23,4.05-.11,6-.97,9.07-3.76,5.44-4.83,34.48-38.54,71.47-83.1,9.77-11.7,20.52-24.48,23.73-28.35,14.8-17.72,19.12-22.87,29.45-35.43,6-7.41,11.73-14.28,12.42-15.25.84-.97,3.63-4.62,6.42-8.05,2.79-3.44,12-15.14,20.52-26.09,8.65-10.95,16.75-21.37,18.29-23.08,2.37-2.79,7.82-9.88,30.85-40.26,37.83-49.6,66.03-95.77,85.43-139.58,14.8-33.5,22.33-68.39,19.26-89.01-3.49-23.08-17.31-40.16-40.06-49.28-16.61-6.55-35.32-8.27-56.25-5.05ZM315.22,264.37\"><\/path><\/svg><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Amamos lo que Hacemos<\/h3><p class=\"icon-box-description\">Atendiendo a todos con amor\n<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6054d6b8\" data-id=\"6054d6b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32518171 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"32518171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module__1_6a5804c9d6068\" ><div class=\"jkit-icon-box-wrapper hover-from-top\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 650 650\"><defs><style>      .cls-1 {        fill: url(#radial-gradient);      }      .cls-1, .cls-2, .cls-3 {        mix-blend-mode: screen;        opacity: .4;      }      .cls-4 {        isolation: isolate;      }      .cls-5 {        fill: #184c95;      }      .cls-2 {        fill: url(#radial-gradient-2);      }      .cls-3 {        fill: url(#radial-gradient-3);      }    <\/style><radialGradient id=\"radial-gradient\" cx=\"323.09\" cy=\"494.63\" fx=\"323.09\" fy=\"494.63\" r=\"397.26\" gradientTransform=\"translate(-1.04)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\".31\" stop-color=\"#fff\"><\/stop><stop offset=\"1\" stop-color=\"#010101\"><\/stop><\/radialGradient><radialGradient id=\"radial-gradient-2\" cx=\"115.18\" cy=\"449.29\" fx=\"115.18\" fy=\"449.29\" r=\"122.01\" xlink:href=\"#radial-gradient\"><\/radialGradient><radialGradient id=\"radial-gradient-3\" cx=\"493.66\" cy=\"480.76\" fx=\"493.66\" fy=\"480.76\" r=\"304.04\" xlink:href=\"#radial-gradient\"><\/radialGradient><\/defs><g class=\"cls-4\"><g id=\"Capa_1\" data-name=\"Capa 1\"><g><path class=\"cls-5\" d=\"M327.28,193.3l34.96,70.66c1.39,2.82,4.09,4.77,7.21,5.22l78.16,11.33c7.85,1.14,10.98,10.76,5.3,16.29l-56.56,55c-2.26,2.19-3.28,5.35-2.75,8.45l13.35,77.66c1.34,7.8-6.87,13.75-13.89,10.07l-69.91-36.67c-2.79-1.46-6.12-1.46-8.91,0l-69.91,36.67c-7.02,3.68-15.23-2.27-13.89-10.07l13.35-77.66c.53-3.1-.5-6.26-2.75-8.45l-56.56-55c-5.68-5.52-2.55-15.15,5.3-16.29l78.16-11.33c3.12-.45,5.81-2.41,7.21-5.22l34.96-70.66c3.51-7.1,13.65-7.1,17.16,0Z\"><\/path><path class=\"cls-5\" d=\"M78.6,298.77l-6.91,42.54c-.5,3.1-2.5,5.76-5.35,7.1l-39.04,18.44c-7.17,3.39-7.33,13.51-.28,17.12l38.42,19.7c2.8,1.44,4.72,4.16,5.12,7.27l5.52,42.74c1.01,7.85,10.61,11.13,16.24,5.56l30.65-30.37c2.24-2.21,5.42-3.19,8.51-2.61l42.45,7.97c7.8,1.46,13.89-6.62,10.31-13.69l-19.48-38.46c-1.42-2.81-1.37-6.13.14-8.89l20.72-37.81c3.8-6.94-2.02-15.23-9.86-14.02l-42.69,6.59c-3.11.48-6.26-.6-8.43-2.88l-29.64-31.34c-5.44-5.76-15.14-2.79-16.41,5.03Z\"><\/path><path class=\"cls-5\" d=\"M559.35,298.77l6.91,42.54c.5,3.1,2.5,5.76,5.35,7.1l39.04,18.44c7.17,3.39,7.33,13.51.28,17.12l-38.42,19.7c-2.8,1.44-4.72,4.16-5.12,7.27l-5.52,42.74c-1.01,7.85-10.61,11.13-16.24,5.56l-30.65-30.37c-2.24-2.21-5.42-3.19-8.51-2.61l-42.45,7.97c-7.8,1.46-13.89-6.62-10.31-13.69l19.48-38.46c1.42-2.81,1.37-6.13-.14-8.89l-20.72-37.81c-3.8-6.94,2.02-15.23,9.86-14.02l42.69,6.59c3.11.48,6.26-.6,8.43-2.88l29.64-31.34c5.44-5.76,15.14-2.79,16.41,5.03Z\"><\/path><path class=\"cls-1\" d=\"M228.78,447.65c2.92-8.92,6.59-17.63,11.03-26.14.19-.36.35-.74.48-1.13,9.2-27.89,24.81-52.04,46.84-72.45,41.25-41.15,102.52-66.47,160.84-66.47,2.54,0,5.04.11,7.56.2l-86.08-12.48c-3.12-.45-5.81-2.41-7.21-5.22l-34.96-70.66c-3.51-7.1-13.65-7.1-17.16,0l-34.96,70.66c-1.39,2.82-4.09,4.77-7.21,5.22l-78.16,11.33c-7.85,1.14-10.98,10.76-5.3,16.29l56.56,55c2.26,2.19,3.28,5.35,2.75,8.45l-15.02,87.39Z\"><\/path><path class=\"cls-2\" d=\"M91.17,432.17c.19-.36.35-.73.47-1.12,9.2-27.89,24.81-52.04,46.84-72.45,5.73-5.71,11.84-11.12,18.28-16.19,7.76-6.11,2.46-18.48-7.31-16.97l-16.38,2.53c-3.11.48-6.26-.6-8.43-2.88l-29.64-31.34c-5.44-5.76-15.14-2.79-16.41,5.03l-6.9,42.54c-.5,3.1-2.5,5.76-5.35,7.1l-39.04,18.44c-7.17,3.39-7.33,13.51-.28,17.12l38.42,19.7c2.8,1.44,4.72,4.16,5.12,7.27l2.39,18.53c1.21,9.36,13.69,11.41,18.04,3.03.06-.11.12-.22.18-.34Z\"><\/path><path class=\"cls-3\" d=\"M465.5,397.28c-4.4,8.68,5.44,17.48,13.71,12.32,36.53-22.84,80.15-36.05,122.26-36.05,9,0,17.84.61,26.54,1.68l.17-.09-56.57-26.72c-2.85-1.34-4.85-4-5.35-7.1l-6.9-42.54c-1.27-7.81-10.96-10.78-16.41-5.03l-29.64,31.34c-2.16,2.29-5.31,3.36-8.43,2.88l-42.69-6.59c-7.84-1.21-13.67,7.07-9.86,14.02l20.72,37.81c1.51,2.76,1.57,6.08.14,8.89l-7.69,15.19Z\"><\/path><\/g><\/g><\/g><\/svg><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Marcamos la Diferencia<\/h3><p class=\"icon-box-description\">Mejoramos constantemente, marcando tendencias en el sector salud.<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-93188fc\" data-id=\"93188fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ed513a7 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"7ed513a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module__2_6a5804c9d7c1d\" ><div class=\"jkit-icon-box-wrapper hover-from-bottom\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" data-name=\"Capa 1\" viewBox=\"0 0 650 650\"><defs><style>      .cls-1 {        fill: #184c95;      }      .cls-2 {        fill: #204070;      }    <\/style><\/defs><g><polygon class=\"cls-1\" points=\"188.71 401.01 329.83 494.52 622.83 130.71 188.71 401.01\"><\/polygon><polygon class=\"cls-1\" points=\"124.46 358.43 622.83 130.71 27.17 293.96 124.46 358.43\"><\/polygon><\/g><g><polygon class=\"cls-2\" points=\"272 456.2 329.83 494.52 622.83 130.71 272 456.2\"><\/polygon><polygon class=\"cls-2\" points=\"124.46 358.43 622.83 130.71 73.86 324.9 124.46 358.43\"><\/polygon><\/g><g><path class=\"cls-1\" d=\"M188.72,406.78c-1.93,0-3.82-.96-4.92-2.72-1.69-2.71-.87-6.27,1.85-7.96l357.75-222.74L126.87,363.68c-2.91,1.33-6.34.05-7.68-2.85-1.33-2.9-.05-6.33,2.85-7.66l498.37-227.72c2.77-1.27,6.06-.17,7.51,2.51,1.45,2.68.56,6.02-2.03,7.64L191.77,405.91c-.95.59-2.01.88-3.06.88Z\"><\/path><g><path class=\"cls-1\" d=\"M329.82,500.29c-1.1,0-2.22-.31-3.2-.96l-141.12-93.51c-1.64-1.09-2.61-2.93-2.59-4.89.03-1.96,1.06-3.78,2.73-4.82L619.77,125.81c2.39-1.49,5.52-1.04,7.39,1.07,1.88,2.11,1.95,5.26.18,7.45l-293,363.8c-1.14,1.41-2.82,2.16-4.52,2.16ZM199.4,401.16l129.22,85.63,268.3-333.14-397.53,247.51Z\"><\/path><path class=\"cls-1\" d=\"M124.46,364.21c-1.12,0-2.24-.32-3.2-.96l-97.29-64.47c-1.89-1.25-2.87-3.49-2.51-5.73.36-2.24,1.99-4.05,4.18-4.65L621.3,125.14c2.91-.8,5.94.77,6.98,3.6,1.03,2.83-.29,5.97-3.03,7.23L126.87,363.68c-.77.35-1.59.52-2.41.52ZM40.97,296.17l84.01,55.67,430.34-196.63L40.97,296.17Z\"><\/path><\/g><path class=\"cls-1\" d=\"M168.43,525.06c-.59,0-1.18-.09-1.75-.27-1.88-.59-3.32-2.09-3.84-3.99l-43.97-160.86c-.84-3.08.98-6.25,4.06-7.09,3.07-.85,6.27.97,7.11,4.05l41.61,152.22,81.63-67.34c2.47-2.04,6.12-1.68,8.15.77,2.04,2.46,1.69,6.1-.77,8.13l-88.55,73.05c-1.05.87-2.36,1.33-3.69,1.33Z\"><\/path><path class=\"cls-1\" d=\"M168.44,525.06c-.32,0-.65-.03-.98-.08-3.15-.54-5.27-3.52-4.73-6.67l20.28-118.28c.54-3.15,3.53-5.27,6.68-4.72,3.15.54,5.27,3.52,4.73,6.67l-20.28,118.28c-.48,2.81-2.93,4.8-5.7,4.8Z\"><\/path><\/g><\/svg><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Lo Hacemos Posible<\/h3><p class=\"icon-box-description\">Hacemos que las cosas pasen, de manera \u00e1gil y eficiente.<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85ddf66 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"85ddf66\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06105b0\" data-id=\"06105b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee9a28d elementor-widget elementor-widget-spacer\" data-id=\"ee9a28d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Servicios Tecnolog\u00eda en Salud Realizamos el suministro, transporte e instalaci\u00f3n de tecnolog\u00eda en salud (equipos biom\u00e9dicos, biom\u00e9tricos, insumos, dispositivos) y materiales necesarios para completar una \u00f3ptima recuperaci\u00f3n del paciente en su domicilio. Concentradores Balas de ox\u00edgeno Aspiradores Nebulizadores Bombas de infusi\u00f3n B-PAP C-PAP Camas hospitalarias Colchones anti escaras Bombas de sistema de presi\u00f3n negativa Monitores de signos vitales Ventiladores Transformamos vidas, brindando con pasio\u0301n, servicios c\u00e1lidos y efectivos. Nuestros Atributos de Cultura Comprometidos con el bienestar de todos Amamos lo que Hacemos Atendiendo a todos con amor Marcamos la Diferencia Mejoramos constantemente, marcando tendencias en el sector salud. Lo Hacemos Posible Hacemos que las cosas pasen, de manera \u00e1gil y eficiente. Concentradores Balas de ox\u00edgeno Aspiradores Nebulizadores Bombas de infusi\u00f3n B-PAP C-PAP Camas hospitalarias Colchones anti escaras Bombas de sistema de presi\u00f3n negativa Monitores de signos vitales Ventiladores Transformamos vidas, brindando con pasio\u0301n, servicios c\u00e1lidos y efectivos. Nuestros Atributos de Cultura Comprometidos con el bienestar de todos Amamos lo que Hacemos Atendiendo a todos con amor Marcamos la Diferencia Mejoramos constantemente, marcando tendencias en el sector salud. Lo Hacemos Posible Hacemos que las cosas pasen, de manera \u00e1gil y eficiente.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_angie_page":false,"footnotes":""},"class_list":["post-497","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":28,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages\/497\/revisions"}],"predecessor-version":[{"id":7542,"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/pages\/497\/revisions\/7542"}],"wp:attachment":[{"href":"https:\/\/cuidadoseguro.com.co\/csc3\/wp-json\/wp\/v2\/media?parent=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}